{"id":25085,"date":"2025-12-10T20:56:14","date_gmt":"2025-12-10T23:56:14","guid":{"rendered":"https:\/\/www.hidrocentro.cl\/laserena\/?post_type=product&#038;p=25085"},"modified":"2025-12-10T20:56:20","modified_gmt":"2025-12-10T23:56:20","slug":"camara-cloradora-170-l-amerplast","status":"publish","type":"product","link":"https:\/\/www.hidrocentro.cl\/laserena\/producto\/camara-cloradora-170-l-amerplast\/","title":{"rendered":"C\u00e1mara Cloradora 170 L Amerplast"},"content":{"rendered":"<div id=\"div_block-97-79\" class=\"ct-div-block\">\n<div id=\"div_block-39-79\" class=\"ct-div-block\">\n<div id=\"text_block-40-79\" class=\"ct-text-block\">DIMENSIONES<\/div>\n<div id=\"text_block-41-79\" class=\"ct-text-block\">\n<p>Altura: 700 mm<\/p>\n<p>Di\u00e1metro: 600 mm<\/p>\n<\/div>\n<\/div>\n<div id=\"div_block-36-79\" class=\"ct-div-block\">\n<div id=\"text_block-37-79\" class=\"ct-text-block\">CARACTER\u00cdSTICAS<\/div>\n<div id=\"text_block-38-79\" class=\"ct-text-block\">\n<ul>\n<li>C\u00e1mara de polietileno de 170 litros de volumen total<\/li>\n<li>Codos de PVC 110 mm para entrada y salida con sus respectivos sellos de goma<\/li>\n<li>Cartridge con sello de goma para ingreso de las pastillas de cloraci\u00f3n (color blanco)<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>DIMENSIONES Altura: 700 mm Di\u00e1metro: 600 mm CARACTER\u00cdSTICAS C\u00e1mara de polietileno de 170 litros de volumen total Codos de PVC 110 mm para entrada y salida con sus respectivos sellos [&hellip;]<\/p>\n","protected":false},"featured_media":25112,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-25085","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-camaras-para-fosas"],"_links":{"self":[{"href":"https:\/\/www.hidrocentro.cl\/laserena\/wp-json\/wp\/v2\/product\/25085"}],"collection":[{"href":"https:\/\/www.hidrocentro.cl\/laserena\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.hidrocentro.cl\/laserena\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hidrocentro.cl\/laserena\/wp-json\/wp\/v2\/comments?post=25085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hidrocentro.cl\/laserena\/wp-json\/wp\/v2\/media\/25112"}],"wp:attachment":[{"href":"https:\/\/www.hidrocentro.cl\/laserena\/wp-json\/wp\/v2\/media?parent=25085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}